{"id":3888,"date":"2023-04-02T10:54:45","date_gmt":"2023-04-02T10:54:45","guid":{"rendered":"https:\/\/chispalcv.org\/lcv-y-chispa-apoyan-a-la-donald-mceachin-environmental-justice-for-all-act\/"},"modified":"2023-04-02T10:54:45","modified_gmt":"2023-04-02T10:54:45","slug":"lcv-y-chispa-apoyan-a-la-donald-mceachin-environmental-justice-for-all-act","status":"publish","type":"post","link":"https:\/\/chispalcv.org\/es\/lcv-y-chispa-apoyan-a-la-donald-mceachin-environmental-justice-for-all-act\/","title":{"rendered":"LCV y Chispa apoyan A. la Donald McEachin Environmental Justice for All Act"},"content":{"rendered":"<p><b>Contacto<\/b>: Emily Samsel |\u00a0<a href=\"esamsel@lcv.org\">esamsel@lcv.org<\/a> | 828-713-9647<\/p>\n<p><span style=\"font-weight: 400;\"><strong>Washington, D.C.<\/strong> \u2013 En respuesta a la introducci\u00f3n de la A. Donald McEachin Environmental Justice for All Act hoy, The League of Conservatoin Voters (LCV) se enorgulleci\u00f3 de unirse a la declaraci\u00f3n grupal del <\/span><a href=\"https:\/\/ajustclimate.org\/pressrelease.html?pId=1035\"><span style=\"font-weight: 400;\">Foro Nacional sobre el Clima Equitativo y Justo<\/span><\/a><span style=\"font-weight: 400;\">. Adicionalmente, LCV y Chispa emitieron los siguientes comunicados:<\/span><\/p>\n<p><b>Sara Chieffo, Vicepresidenta de Asuntos Gubernamentales de LCV:<\/b><\/p>\n<p><span style=\"font-weight: 400;\">[No hay mejor manera de honrar el legado del congresista Donald McEachin que aprobar y promulgar su legislaci\u00f3n emblem\u00e1tica que ahora lleva el nombre del difunto congresista. Fundamentalmente, esta amplia legislaci\u00f3n de justicia ambiental garantizar\u00eda que el aporte de la comunidad sea central para el desarrollo de todos los nuevos proyectos de energ\u00eda, adem\u00e1s de las muchas pol\u00edticas antirracistas importantes en la Ley que abordan las desigualdades de larga data en nuestras protecciones ambientales. Deber\u00edamos aprobar la A. Donald McEachin Environmental Justice for All Act en lugar de la destructiva Ley de Contaminadores por encima de las Personas de los Republicanos de la C\u00e1mara. LCV elogia el liderazgo del representante Ra\u00fal Grijalva, el difunto representante Donald McEachin, la representante Barbara Lee, la representante Sydney Kamlager-Dove, los senadores Tammy Duckworth y Cory Booker, y los cientos de activistas ambientales involucrados en redactar y promover el informe ambiental m\u00e1s completo. legislaci\u00f3n de justicia en la historia de los Estados Unidos]<\/span><\/p>\n<p><b>Directora Nacional de Chispa Estefany Carrasco-Gonz\u00e1lez:<\/b><\/p>\n<p><span style=\"font-weight: 400;\">[Chispa LCV da la bienvenida a la reintroducci\u00f3n de la A. la Donald McEachin Environmental Justice for All Act<\/span> <span style=\"font-weight: 400;\">como el esfuerzo m\u00e1s importante para abordar d\u00e9cadas de racismo ambiental. Instamos al Comit\u00e9 de Recursos Naturales de la C\u00e1mara de Representantes a que promueva este proyecto de ley sin demora y promulgue estas soluciones pol\u00edticas que le dar\u00e1n a la comunidad, especialmente a aquellos que son los m\u00e1s afectados por el cambio clim\u00e1tico, m\u00e1s poder para determinar la salud ambiental y p\u00fablica de los lugares donde trabajamos, jugamos. , vivir, aprender y pasar tiempo con nuestras familias. Cuatro a\u00f1os despu\u00e9s de la introducci\u00f3n inicial, la necesidad imperiosa de nuestras comunidades de obtener soluciones ambientales es cada vez m\u00e1s cr\u00edtica.]<\/span><\/p>\n<p style=\"text-align: center;\">###<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Washington, D.C. \u2013 En respuesta a la introducci\u00f3n de la A. Donald McEachin Environmental Justice for All Act&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[82,78],"tags":[],"class_list":["post-3888","post","type-post","status-publish","format-standard","hentry","category-atmosfera-limpia","category-justicia-medioambiental"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/posts\/3888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/comments?post=3888"}],"version-history":[{"count":0,"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/posts\/3888\/revisions"}],"wp:attachment":[{"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/media?parent=3888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/categories?post=3888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/tags?post=3888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}