{"id":5068,"date":"2024-09-13T18:48:23","date_gmt":"2024-09-13T18:48:23","guid":{"rendered":"https:\/\/chispalcv.org\/sin-luz-pero-no-a-oscuras\/"},"modified":"2024-09-13T18:48:23","modified_gmt":"2024-09-13T18:48:23","slug":"sin-luz-pero-no-a-oscuras","status":"publish","type":"post","link":"https:\/\/chispalcv.org\/es\/sin-luz-pero-no-a-oscuras\/","title":{"rendered":"Sin luz, pero no a oscuras"},"content":{"rendered":"<p>Este verano, poco despu\u00e9s de iniciar mi pasant\u00eda con LCV y Chispa, toda mi familia en Houston estaba en m\u00e1xima alerta. Esto era porque un hurac\u00e1n se dirig\u00eda a la zona. La \u00faltima vez que tuvimos una tormenta, hubo una gran inundaci\u00f3n y estuvimos sin luz durante unos cuatro d\u00edas, as\u00ed que est\u00e1bamos preocupados.<\/p>\n<p>Por suerte, hemos aprendido de experiencias pasadas; y ahora mi familia cercana (mi mam\u00e1, mi hermana y yo) estamos siempre listos para cualquier tormenta que se avecine. Aunque todav\u00eda me preparaba para un posible corte de luz, cuanto m\u00e1s le\u00eda, m\u00e1s parec\u00eda que la tormenta se hab\u00eda calmado y que no nos afectar\u00eda.<\/p>\n<p>Esto no fue lo que sucedi\u00f3, especialmente cuando me dorm\u00ed. Durante las ocho horas que estuve dormido, la tormenta tropical se convirti\u00f3 en hurac\u00e1n y su trayectoria cambi\u00f3. Estaba impactando directamente el \u00e1rea de Houston, y a las 5 de la ma\u00f1ana me despert\u00e9 empapado en sudor porque se nos hab\u00eda ido la electricidad por completo. Por suerte, ya hab\u00eda enviado un correo a mis supervisores anticipando que esto podr\u00eda ocurrir, pero esto solo fue el inicio de un largo y arduo proceso para sobrevivir a las secuelas del hurac\u00e1n Beryl.<\/p>\n<p>El calor dentro de la casa comenz\u00f3 a intensificarse. Hac\u00eda tanto calor que pasar el d\u00eda afuera bajo el sol era preferible a estar dentro de nuestra \u00abcasa horno\u00bb, como la llamaba mi hermana. Si alguna vez has estado en Houston durante el verano, sabes que pasar m\u00e1s de un par de horas bajo el sol, incluso con sombra, puede ser extremadamente agobiante.<\/p>\n<p>Al comenzar nuestro primer d\u00eda sin electricidad, vimos las noticias en nuestros tel\u00e9fonos y nos dimos cuenta de que \u00e1rboles hab\u00edan ca\u00eddo por toda la ciudad, da\u00f1ando gran parte de la infraestructura. Nos enteramos de que parte de estos da\u00f1os por el viento ocurrieron justo afuera de nuestra casa, incluyendo los techos de muchos de nuestros vecinos que se desprendieron de sus casas. Les ayudamos a colocar partes de sus techos que encontramos en el suelo en nuestro patio trasero para evitar que los fuertes vientos los alejaran a\u00fan m\u00e1s. Los reportes de noticias mostraban un panorama de la ciudad en caos, con \u00e1rboles cayendo sobre casas y cortes de electricidad que afectaban a 2.7 millones de personas en Houston.<\/p>\n<p>Nos dimos cuenta de que probablemente no tendr\u00edamos luz al menos ese d\u00eda. A medida que avanzaba el d\u00eda, la esperanza de recuperar la electricidad disminu\u00eda a\u00fan m\u00e1s, y nos dimos cuenta de que no ten\u00edamos idea de cu\u00e1ndo regresar\u00eda. Este sentimiento lo compart\u00edan muchas personas en el \u00e1rea. Escuchamos que ya hab\u00eda personas y negocios con electricidad de nuevo.<\/p>\n<p>El calor era insoportable, as\u00ed que decid\u00ed buscar aire acondicionado y electricidad para cargar mi laptop y mi tel\u00e9fono. Fuimos a algunos negocios locales cerca del centro y not\u00e9 un patr\u00f3n. Las \u00e1reas de mayores ingresos sol\u00edan recuperar la electricidad antes. Los negocios y hogares en mi comunidad, que es diversa y de clase media, a\u00fan no ten\u00edan electricidad. Al investigar m\u00e1s, descubr\u00ed que la mayor\u00eda de las personas en vecindarios m\u00e1s adinerados ten\u00edan generadores; mientras que en otros, la mayor\u00eda no contaba con uno.<\/p>\n<p>Mientras cargaba mis dispositivos electr\u00f3nicos en la cafeter\u00eda, me di cuenta de que <i>CenterPoint Energy<\/i> ten\u00eda el monopolio de la energ\u00eda en Houston. La falta de electricidad se deb\u00eda a la falta de regulaci\u00f3n y diversificaci\u00f3n en la red el\u00e9ctrica de Houston. Todo esto me llev\u00f3 a entender los eventos que han afectado a Houston y Texas en el pasado desde una nueva perspectiva. La ausencia de supervisi\u00f3n gubernamental agrav\u00f3 los problemas.<\/p>\n<p>Est\u00e1bamos muy desesperados por encontrar un poco de alivio en el tercer d\u00eda sin electricidad. Tuvimos suerte al encontrar un restaurante cercano que estaba ofreciendo almuerzo, y fue como estar en el para\u00edso. El aire acondicionado estaba funcionando al m\u00e1ximo. Finalmente, me sent\u00ed relajado leyendo, mientras mi hermana y mi mam\u00e1 conversaban sobre la universidad a la que quer\u00eda ir mi hermana. Despu\u00e9s de un largo d\u00eda leyendo y comiendo en el restaurante con aire acondicionado, decidimos regresar a casa. Al llegar, la situaci\u00f3n segu\u00eda siendo dif\u00edcil. Fui a nadar a la piscina local para refrescarme. Cuando regres\u00e9 a casa alrededor de la hora de la cena, \u00a1la electricidad hab\u00eda vuelto finalmente!<\/p>\n<p>El term\u00f3metro indicaba que la temperatura en la casa hab\u00eda subido a unos insoportables 95 grados. Era como un milagro que la electricidad hubiera vuelto, y todos est\u00e1bamos celebrando como si la electricidad fuera algo que nunca antes hab\u00edamos tenido.<\/p>\n<p>A medida que pasaban los d\u00edas e incluso las semanas, m\u00e1s y m\u00e1s habitantes de Houston empezaron a recuperar la electricidad. Esto era una buena noticia, pero debido a los masivos cortes de energ\u00eda, Houston sufri\u00f3 36 muertes que podr\u00edan haberse evitado.<\/p>\n<p>Muchas de esas muertes fueron consecuencia de los cortes de energ\u00eda provocados por la falta de preparaci\u00f3n de <i>CenterPoint<\/i> ante el hurac\u00e1n. Aunque el gobernador ha anunciado una investigaci\u00f3n sobre <i>CenterPoint,<\/i> no estoy seguro si el gobierno tomar\u00e1 realmente alguna acci\u00f3n.<\/p>\n<p>A medida que el cambio clim\u00e1tico empeora, no podemos depender \u00fanicamente del gobierno para solucionar los problemas. Chispa y LCV est\u00e1n trabajando directamente en estados como Texas para organizar comunidades y empoderarlas para enfrentar estos problemas regionales. Por ejemplo, <a href=\"https:\/\/chispatx.org\/\"><span class=\"s1\">Chispa Texas<\/span><\/a> est\u00e1 colaborando con organizadores comunitarios para fortalecer el poder local contra la contaminaci\u00f3n del aire en todas las comunidades, especialmente en las comunidades de color. Esta contaminaci\u00f3n proveniente de refiner\u00edas y de las grandes petroleras agrava el cambio clim\u00e1tico y provoca huracanes m\u00e1s fuertes y costosos, como el Beryl, que devastan nuestras comunidades.<\/p>\n<p>Al hacer pr\u00e1cticas en Chispa, he trabajado en soluciones orientadas a la comunidad, como la creaci\u00f3n de memorandos para el Congreso sobre autobuses escolares el\u00e9ctricos y la presentaci\u00f3n de mis recomendaciones ambientales a la organizaci\u00f3n LCV. He visto de cerca c\u00f3mo podemos hacer una diferencia en el medio ambiente y en nuestras comunidades.<\/p>\n<p>Este verano, he entendido por qu\u00e9 el trabajo que hemos hecho estos \u00faltimos meses puede salvar vidas. Agradezco a Chispa por permitirme trabajar con una organizaci\u00f3n que ayuda a crear un entorno donde las futuras generaciones no tendr\u00e1n que preocuparse por apagones debido a huracanes, contaminaci\u00f3n masiva del aire por f\u00e1bricas o por no ser escuchados por su gobierno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este verano, poco despu\u00e9s de iniciar mi pasant\u00eda con LCV y Chispa, toda mi familia en Houston estaba en m\u00e1xima alerta. Esto era porque un hurac\u00e1n se dirig\u00eda a la zona. La \u00faltima vez que tuvimos una tormenta, hubo una gran inundaci\u00f3n y estuvimos sin luz durante unos cuatro d\u00edas, as\u00ed que est\u00e1bamos preocupados. Por suerte, hemos aprendido de experiencias pasadas; y ahora mi familia cercana (mi mam\u00e1, mi hermana y yo) estamos siempre listos para cualquier tormenta que se avecine. Aunque todav\u00eda me preparaba para un posible corte de luz, cuanto m\u00e1s le\u00eda, m\u00e1s parec\u00eda que la tormenta se hab\u00eda calmado y que no nos afectar\u00eda. Esto no fue lo que sucedi\u00f3, especialmente cuando me dorm\u00ed. Durante las ocho horas que estuve dormido, la tormenta tropical se convirti\u00f3 en hurac\u00e1n y su trayectoria cambi\u00f3. Estaba impactando directamente el \u00e1rea de Houston, y a las 5 de la ma\u00f1ana me despert\u00e9 empapado en sudor porque se nos hab\u00eda ido la electricidad por completo. Por suerte, ya hab\u00eda enviado un correo a mis supervisores anticipando que esto podr\u00eda ocurrir, pero esto solo fue el inicio de un largo y arduo proceso para sobrevivir a las secuelas del hurac\u00e1n Beryl. El calor dentro de la casa comenz\u00f3 a intensificarse. Hac\u00eda tanto calor que pasar el d\u00eda afuera bajo el sol era preferible a estar dentro de nuestra \u00abcasa horno\u00bb, como la llamaba mi hermana. Si alguna vez has estado en Houston durante el verano, sabes que pasar m\u00e1s de un par de horas bajo el sol, incluso con sombra, puede ser extremadamente agobiante. Al comenzar nuestro primer d\u00eda sin electricidad, vimos las noticias en nuestros tel\u00e9fonos y nos dimos cuenta de que \u00e1rboles hab\u00edan ca\u00eddo por toda la ciudad, da\u00f1ando gran parte de la infraestructura. Nos enteramos de que parte de estos da\u00f1os por el viento ocurrieron justo afuera de nuestra casa, incluyendo los techos de muchos de nuestros vecinos que se desprendieron de sus casas. Les ayudamos a colocar partes de sus techos que encontramos en el suelo en nuestro patio trasero para evitar que los fuertes vientos los alejaran a\u00fan m\u00e1s. Los reportes de noticias mostraban un panorama de la ciudad en caos, con \u00e1rboles cayendo sobre casas y cortes de electricidad que afectaban a 2.7 millones de personas en Houston. Nos dimos cuenta de que probablemente no tendr\u00edamos luz al menos ese d\u00eda. A medida que avanzaba el d\u00eda, la esperanza de recuperar la electricidad disminu\u00eda a\u00fan m\u00e1s, y nos dimos cuenta de que no ten\u00edamos idea de cu\u00e1ndo regresar\u00eda. Este sentimiento lo compart\u00edan muchas personas en el \u00e1rea. Escuchamos que ya hab\u00eda personas y negocios con electricidad de nuevo. El calor era insoportable, as\u00ed que decid\u00ed buscar aire acondicionado y electricidad para cargar mi laptop y mi tel\u00e9fono. Fuimos a algunos negocios locales cerca del centro y not\u00e9 un patr\u00f3n. Las \u00e1reas de mayores ingresos sol\u00edan recuperar la electricidad antes. Los negocios y hogares en mi comunidad, que es diversa y de clase media, a\u00fan no ten\u00edan electricidad. Al investigar m\u00e1s, descubr\u00ed que la mayor\u00eda de las personas en vecindarios m\u00e1s adinerados ten\u00edan generadores; mientras que en otros, la mayor\u00eda no contaba con uno. Mientras cargaba mis dispositivos electr\u00f3nicos en la cafeter\u00eda, me di cuenta de que CenterPoint Energy ten\u00eda el monopolio de la energ\u00eda en Houston. La falta de electricidad se deb\u00eda a la falta de regulaci\u00f3n y diversificaci\u00f3n en la red el\u00e9ctrica de Houston. Todo esto me llev\u00f3 a entender los eventos que han afectado a Houston y Texas en el pasado desde una nueva perspectiva. La ausencia de supervisi\u00f3n gubernamental agrav\u00f3 los problemas. Est\u00e1bamos muy desesperados por encontrar un poco de alivio en el tercer d\u00eda sin electricidad. Tuvimos suerte al encontrar un restaurante cercano que estaba ofreciendo almuerzo, y fue como estar en el para\u00edso. El aire acondicionado estaba funcionando al m\u00e1ximo. Finalmente, me sent\u00ed relajado leyendo, mientras mi hermana y mi mam\u00e1 conversaban sobre la universidad a la que quer\u00eda ir mi hermana. Despu\u00e9s de un largo d\u00eda leyendo y comiendo en el restaurante con aire acondicionado, decidimos regresar a casa. Al llegar, la situaci\u00f3n segu\u00eda siendo dif\u00edcil. Fui a nadar a la piscina local para refrescarme. Cuando regres\u00e9 a casa alrededor de la hora de la cena, \u00a1la electricidad hab\u00eda vuelto finalmente! El term\u00f3metro indicaba que la temperatura en la casa hab\u00eda subido a unos insoportables 95 grados. Era como un milagro que la electricidad hubiera vuelto, y todos est\u00e1bamos celebrando como si la electricidad fuera algo que nunca antes hab\u00edamos tenido. A medida que pasaban los d\u00edas e incluso las semanas, m\u00e1s y m\u00e1s habitantes de Houston empezaron a recuperar la electricidad. Esto era una buena noticia, pero debido a los masivos cortes de energ\u00eda, Houston sufri\u00f3 36 muertes que podr\u00edan haberse evitado. Muchas de esas muertes fueron consecuencia de los cortes de energ\u00eda provocados por la falta de preparaci\u00f3n de CenterPoint ante el hurac\u00e1n. Aunque el gobernador ha anunciado una investigaci\u00f3n sobre CenterPoint, no estoy seguro si el gobierno tomar\u00e1 realmente alguna acci\u00f3n. A medida que el cambio clim\u00e1tico empeora, no podemos depender \u00fanicamente del gobierno para solucionar los problemas. Chispa y LCV est\u00e1n trabajando directamente en estados como Texas para organizar comunidades y empoderarlas para enfrentar estos problemas regionales. Por ejemplo, Chispa Texas est\u00e1 colaborando con organizadores comunitarios para fortalecer el poder local contra la contaminaci\u00f3n del aire en todas las comunidades, especialmente en las comunidades de color. Esta contaminaci\u00f3n proveniente de refiner\u00edas y de las grandes petroleras agrava el cambio clim\u00e1tico y provoca huracanes m\u00e1s fuertes y costosos, como el Beryl, que devastan nuestras comunidades. Al hacer pr\u00e1cticas en Chispa, he trabajado en soluciones orientadas a la comunidad, como la creaci\u00f3n de memorandos para el Congreso sobre autobuses escolares el\u00e9ctricos y la presentaci\u00f3n de mis recomendaciones ambientales a la organizaci\u00f3n LCV. He visto de cerca c\u00f3mo podemos hacer una diferencia en el medio ambiente y en nuestras comunidades. Este verano, he entendido por qu\u00e9 el trabajo que hemos hecho estos \u00faltimos meses puede salvar vidas. Agradezco a<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[78,68,3,126],"tags":[],"class_list":["post-5068","post","type-post","status-publish","format-standard","hentry","category-justicia-medioambiental","category-latinx-poder-es","category-sin-categorizar","category-social-justice-es"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Este verano, poco despu\u00e9s de iniciar mi pasant\u00eda con LCV y Chispa, toda mi familia en Houston estaba en m\u00e1xima alerta. Esto era porque un hurac\u00e1n se dirig\u00eda a la zona. La \u00faltima vez que tuvimos una tormenta, hubo una gran inundaci\u00f3n y estuvimos sin luz durante unos cuatro d\u00edas, as\u00ed que est\u00e1bamos preocupados. Por\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Nicolas Thompson\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/chispalcv.org\/es\/sin-luz-pero-no-a-oscuras\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Chispa | League of Conservation Voters -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sin luz, pero no a oscuras - Chispa | League of Conservation Voters\" \/>\n\t\t<meta property=\"og:description\" content=\"Este verano, poco despu\u00e9s de iniciar mi pasant\u00eda con LCV y Chispa, toda mi familia en Houston estaba en m\u00e1xima alerta. Esto era porque un hurac\u00e1n se dirig\u00eda a la zona. La \u00faltima vez que tuvimos una tormenta, hubo una gran inundaci\u00f3n y estuvimos sin luz durante unos cuatro d\u00edas, as\u00ed que est\u00e1bamos preocupados. Por\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/chispalcv.org\/es\/sin-luz-pero-no-a-oscuras\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/chispalcv.org\/wp-content\/uploads\/2023\/04\/chispaLCV.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/chispalcv.org\/wp-content\/uploads\/2023\/04\/chispaLCV.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1199\" \/>\n\t\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-09-13T18:48:23+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-09-13T18:48:23+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sin luz, pero no a oscuras - Chispa | League of Conservation Voters\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Este verano, poco despu\u00e9s de iniciar mi pasant\u00eda con LCV y Chispa, toda mi familia en Houston estaba en m\u00e1xima alerta. Esto era porque un hurac\u00e1n se dirig\u00eda a la zona. La \u00faltima vez que tuvimos una tormenta, hubo una gran inundaci\u00f3n y estuvimos sin luz durante unos cuatro d\u00edas, as\u00ed que est\u00e1bamos preocupados. Por\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/chispalcv.org\/wp-content\/uploads\/2023\/04\/chispaLCV.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/sin-luz-pero-no-a-oscuras\\\/#blogposting\",\"name\":\"Sin luz, pero no a oscuras - Chispa | League of Conservation Voters\",\"headline\":\"Sin luz, pero no a oscuras\",\"author\":{\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/author\\\/nicolas\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/chispalcv.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Chispa-Logo.png\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/#articleImage\",\"width\":418,\"height\":80,\"caption\":\"Chispa Logo\"},\"datePublished\":\"2024-09-13T18:48:23+00:00\",\"dateModified\":\"2024-09-13T18:48:23+00:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/sin-luz-pero-no-a-oscuras\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/sin-luz-pero-no-a-oscuras\\\/#webpage\"},\"articleSection\":\"Justicia Medioambiental, Latinx Poder, Sin categorizar, Social Justice, Opcional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/sin-luz-pero-no-a-oscuras\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/category\\\/sin-categorizar\\\/#listItem\",\"name\":\"Sin categorizar\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/category\\\/sin-categorizar\\\/#listItem\",\"position\":2,\"name\":\"Sin categorizar\",\"item\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/category\\\/sin-categorizar\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/sin-luz-pero-no-a-oscuras\\\/#listItem\",\"name\":\"Sin luz, pero no a oscuras\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/sin-luz-pero-no-a-oscuras\\\/#listItem\",\"position\":3,\"name\":\"Sin luz, pero no a oscuras\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/category\\\/sin-categorizar\\\/#listItem\",\"name\":\"Sin categorizar\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/#organization\",\"name\":\"Chispa | League of Conservation Voters\",\"url\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/chispalcv.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Chispa-Logo.png\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/sin-luz-pero-no-a-oscuras\\\/#organizationLogo\",\"width\":418,\"height\":80,\"caption\":\"Chispa Logo\"},\"image\":{\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/sin-luz-pero-no-a-oscuras\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/author\\\/nicolas\\\/#author\",\"url\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/author\\\/nicolas\\\/\",\"name\":\"Nicolas Thompson\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/sin-luz-pero-no-a-oscuras\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1ec371bc4cc30103b4125ace36a89aedd9782cc3859d860fea9ce390f66d4d0?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Nicolas Thompson\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/sin-luz-pero-no-a-oscuras\\\/#webpage\",\"url\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/sin-luz-pero-no-a-oscuras\\\/\",\"name\":\"Sin luz, pero no a oscuras - Chispa | League of Conservation Voters\",\"description\":\"Este verano, poco despu\\u00e9s de iniciar mi pasant\\u00eda con LCV y Chispa, toda mi familia en Houston estaba en m\\u00e1xima alerta. Esto era porque un hurac\\u00e1n se dirig\\u00eda a la zona. La \\u00faltima vez que tuvimos una tormenta, hubo una gran inundaci\\u00f3n y estuvimos sin luz durante unos cuatro d\\u00edas, as\\u00ed que est\\u00e1bamos preocupados. Por\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/sin-luz-pero-no-a-oscuras\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/author\\\/nicolas\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/author\\\/nicolas\\\/#author\"},\"datePublished\":\"2024-09-13T18:48:23+00:00\",\"dateModified\":\"2024-09-13T18:48:23+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/\",\"name\":\"Chispa | League of Conservation Voters\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sin luz, pero no a oscuras - Chispa | League of Conservation Voters","description":"Este verano, poco despu\u00e9s de iniciar mi pasant\u00eda con LCV y Chispa, toda mi familia en Houston estaba en m\u00e1xima alerta. Esto era porque un hurac\u00e1n se dirig\u00eda a la zona. La \u00faltima vez que tuvimos una tormenta, hubo una gran inundaci\u00f3n y estuvimos sin luz durante unos cuatro d\u00edas, as\u00ed que est\u00e1bamos preocupados. Por","canonical_url":"https:\/\/chispalcv.org\/es\/sin-luz-pero-no-a-oscuras\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/chispalcv.org\/es\/sin-luz-pero-no-a-oscuras\/#blogposting","name":"Sin luz, pero no a oscuras - Chispa | League of Conservation Voters","headline":"Sin luz, pero no a oscuras","author":{"@id":"https:\/\/chispalcv.org\/es\/author\/nicolas\/#author"},"publisher":{"@id":"https:\/\/chispalcv.org\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/chispalcv.org\/wp-content\/uploads\/2021\/08\/Chispa-Logo.png","@id":"https:\/\/chispalcv.org\/es\/#articleImage","width":418,"height":80,"caption":"Chispa Logo"},"datePublished":"2024-09-13T18:48:23+00:00","dateModified":"2024-09-13T18:48:23+00:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/chispalcv.org\/es\/sin-luz-pero-no-a-oscuras\/#webpage"},"isPartOf":{"@id":"https:\/\/chispalcv.org\/es\/sin-luz-pero-no-a-oscuras\/#webpage"},"articleSection":"Justicia Medioambiental, Latinx Poder, Sin categorizar, Social Justice, Opcional"},{"@type":"BreadcrumbList","@id":"https:\/\/chispalcv.org\/es\/sin-luz-pero-no-a-oscuras\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/chispalcv.org\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/chispalcv.org\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/chispalcv.org\/es\/category\/sin-categorizar\/#listItem","name":"Sin categorizar"}},{"@type":"ListItem","@id":"https:\/\/chispalcv.org\/es\/category\/sin-categorizar\/#listItem","position":2,"name":"Sin categorizar","item":"https:\/\/chispalcv.org\/es\/category\/sin-categorizar\/","nextItem":{"@type":"ListItem","@id":"https:\/\/chispalcv.org\/es\/sin-luz-pero-no-a-oscuras\/#listItem","name":"Sin luz, pero no a oscuras"},"previousItem":{"@type":"ListItem","@id":"https:\/\/chispalcv.org\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/chispalcv.org\/es\/sin-luz-pero-no-a-oscuras\/#listItem","position":3,"name":"Sin luz, pero no a oscuras","previousItem":{"@type":"ListItem","@id":"https:\/\/chispalcv.org\/es\/category\/sin-categorizar\/#listItem","name":"Sin categorizar"}}]},{"@type":"Organization","@id":"https:\/\/chispalcv.org\/es\/#organization","name":"Chispa | League of Conservation Voters","url":"https:\/\/chispalcv.org\/es\/","logo":{"@type":"ImageObject","url":"https:\/\/chispalcv.org\/wp-content\/uploads\/2021\/08\/Chispa-Logo.png","@id":"https:\/\/chispalcv.org\/es\/sin-luz-pero-no-a-oscuras\/#organizationLogo","width":418,"height":80,"caption":"Chispa Logo"},"image":{"@id":"https:\/\/chispalcv.org\/es\/sin-luz-pero-no-a-oscuras\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/chispalcv.org\/es\/author\/nicolas\/#author","url":"https:\/\/chispalcv.org\/es\/author\/nicolas\/","name":"Nicolas Thompson","image":{"@type":"ImageObject","@id":"https:\/\/chispalcv.org\/es\/sin-luz-pero-no-a-oscuras\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/f1ec371bc4cc30103b4125ace36a89aedd9782cc3859d860fea9ce390f66d4d0?s=96&d=mm&r=g","width":96,"height":96,"caption":"Nicolas Thompson"}},{"@type":"WebPage","@id":"https:\/\/chispalcv.org\/es\/sin-luz-pero-no-a-oscuras\/#webpage","url":"https:\/\/chispalcv.org\/es\/sin-luz-pero-no-a-oscuras\/","name":"Sin luz, pero no a oscuras - Chispa | League of Conservation Voters","description":"Este verano, poco despu\u00e9s de iniciar mi pasant\u00eda con LCV y Chispa, toda mi familia en Houston estaba en m\u00e1xima alerta. Esto era porque un hurac\u00e1n se dirig\u00eda a la zona. La \u00faltima vez que tuvimos una tormenta, hubo una gran inundaci\u00f3n y estuvimos sin luz durante unos cuatro d\u00edas, as\u00ed que est\u00e1bamos preocupados. Por","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/chispalcv.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/chispalcv.org\/es\/sin-luz-pero-no-a-oscuras\/#breadcrumblist"},"author":{"@id":"https:\/\/chispalcv.org\/es\/author\/nicolas\/#author"},"creator":{"@id":"https:\/\/chispalcv.org\/es\/author\/nicolas\/#author"},"datePublished":"2024-09-13T18:48:23+00:00","dateModified":"2024-09-13T18:48:23+00:00"},{"@type":"WebSite","@id":"https:\/\/chispalcv.org\/es\/#website","url":"https:\/\/chispalcv.org\/es\/","name":"Chispa | League of Conservation Voters","inLanguage":"es-ES","publisher":{"@id":"https:\/\/chispalcv.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Chispa | League of Conservation Voters -","og:type":"article","og:title":"Sin luz, pero no a oscuras - Chispa | League of Conservation Voters","og:description":"Este verano, poco despu\u00e9s de iniciar mi pasant\u00eda con LCV y Chispa, toda mi familia en Houston estaba en m\u00e1xima alerta. Esto era porque un hurac\u00e1n se dirig\u00eda a la zona. La \u00faltima vez que tuvimos una tormenta, hubo una gran inundaci\u00f3n y estuvimos sin luz durante unos cuatro d\u00edas, as\u00ed que est\u00e1bamos preocupados. Por","og:url":"https:\/\/chispalcv.org\/es\/sin-luz-pero-no-a-oscuras\/","og:image":"https:\/\/chispalcv.org\/wp-content\/uploads\/2023\/04\/chispaLCV.jpg","og:image:secure_url":"https:\/\/chispalcv.org\/wp-content\/uploads\/2023\/04\/chispaLCV.jpg","og:image:width":1199,"og:image:height":630,"article:published_time":"2024-09-13T18:48:23+00:00","article:modified_time":"2024-09-13T18:48:23+00:00","twitter:card":"summary_large_image","twitter:title":"Sin luz, pero no a oscuras - Chispa | League of Conservation Voters","twitter:description":"Este verano, poco despu\u00e9s de iniciar mi pasant\u00eda con LCV y Chispa, toda mi familia en Houston estaba en m\u00e1xima alerta. Esto era porque un hurac\u00e1n se dirig\u00eda a la zona. La \u00faltima vez que tuvimos una tormenta, hubo una gran inundaci\u00f3n y estuvimos sin luz durante unos cuatro d\u00edas, as\u00ed que est\u00e1bamos preocupados. Por","twitter:image":"https:\/\/chispalcv.org\/wp-content\/uploads\/2023\/04\/chispaLCV.jpg"},"aioseo_meta_data":{"post_id":"5068","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-09-13 18:48:23","updated":"2025-06-11 09:47:37","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/chispalcv.org\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/chispalcv.org\/es\/category\/sin-categorizar\/\" title=\"Sin categorizar\">Sin categorizar<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSin luz, pero no a oscuras\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/chispalcv.org\/es\/"},{"label":"Sin categorizar","link":"https:\/\/chispalcv.org\/es\/category\/sin-categorizar\/"},{"label":"Sin luz, pero no a oscuras","link":"https:\/\/chispalcv.org\/es\/sin-luz-pero-no-a-oscuras\/"}],"_links":{"self":[{"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/posts\/5068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/comments?post=5068"}],"version-history":[{"count":0,"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/posts\/5068\/revisions"}],"wp:attachment":[{"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/media?parent=5068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/categories?post=5068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/tags?post=5068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}