{"id":5212,"date":"2024-11-06T18:55:03","date_gmt":"2024-11-06T18:55:03","guid":{"rendered":"https:\/\/chispalcv.org\/declaracion-de-chispa-sobre-las-elecciones\/"},"modified":"2024-11-06T18:55:10","modified_gmt":"2024-11-06T18:55:10","slug":"declaracion-de-chispa-sobre-las-elecciones","status":"publish","type":"post","link":"https:\/\/chispalcv.org\/es\/declaracion-de-chispa-sobre-las-elecciones\/","title":{"rendered":"Declaraci\u00f3n de Chispa sobre las elecciones"},"content":{"rendered":"<p><strong>Declaraci\u00f3n de la directora senior de Chispa, Estefany Carrasco-Gonz\u00e1lez, sobre los resultados de las elecciones:<\/strong><\/p>\n<p>\u201cEstamos decepcionados por el resultado de las elecciones presidenciales, pero persistiremos y seguiremos luchando por nuestras comunidades. Bajo la nueva Administraci\u00f3n Trump, Chispa continuar\u00e1 trabajando a nivel nacional y con nuestras comunidades de primera l\u00ednea en los estados de Chispa para salvaguardar la protecci\u00f3n ambiental y luchar por un mejor clima para nuestras comunidades y nuestros ni\u00f1os.<\/p>\n<p>Todos merecemos aire, agua y comunidades limpios. No dejaremos de organizarnos para un futuro mejor y m\u00e1s limpio y trabajaremos para proteger a todas nuestras familias, vecindarios y el progreso clim\u00e1tico ya logrado en las comunidades m\u00e1s afectadas\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Declaraci\u00f3n de la directora senior de Chispa, Estefany Carrasco-Gonz\u00e1lez, sobre los resultados de las elecciones: \u201cEstamos decepcionados por el resultado de las elecciones presidenciales, pero persistiremos y seguiremos luchando por nuestras comunidades. Bajo la nueva Administraci\u00f3n Trump, Chispa continuar\u00e1 trabajando a nivel nacional y con nuestras comunidades de primera l\u00ednea en los estados de Chispa para salvaguardar la protecci\u00f3n ambiental y luchar por un mejor clima para nuestras comunidades y nuestros ni\u00f1os. Todos merecemos aire, agua y comunidades limpios. No dejaremos de organizarnos para un futuro mejor y m\u00e1s limpio y trabajaremos para proteger a todas nuestras familias, vecindarios y el progreso clim\u00e1tico ya logrado en las comunidades m\u00e1s afectadas\u201d.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[36,78,68],"tags":[93,148,81],"class_list":["post-5212","post","type-post","status-publish","format-standard","hentry","category-press-release-es","category-justicia-medioambiental","category-latinx-poder-es","tag-chispa-es","tag-elections-es","tag-justicia-medioambiental"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Declaraci\u00f3n de la directora senior de Chispa, Estefany Carrasco-Gonz\u00e1lez, sobre los resultados de las elecciones: \u201cEstamos decepcionados por el resultado de las elecciones presidenciales, pero persistiremos y seguiremos luchando por nuestras comunidades. Bajo la nueva Administraci\u00f3n Trump, Chispa continuar\u00e1 trabajando a nivel nacional y con nuestras comunidades de primera l\u00ednea en los estados de Chispa\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Elena Gaona\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/chispalcv.org\/es\/declaracion-de-chispa-sobre-las-elecciones\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Chispa | League of Conservation Voters -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Declaraci\u00f3n de Chispa sobre las elecciones - Chispa | League of Conservation Voters\" \/>\n\t\t<meta property=\"og:description\" content=\"Declaraci\u00f3n de la directora senior de Chispa, Estefany Carrasco-Gonz\u00e1lez, sobre los resultados de las elecciones: \u201cEstamos decepcionados por el resultado de las elecciones presidenciales, pero persistiremos y seguiremos luchando por nuestras comunidades. Bajo la nueva Administraci\u00f3n Trump, Chispa continuar\u00e1 trabajando a nivel nacional y con nuestras comunidades de primera l\u00ednea en los estados de Chispa\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/chispalcv.org\/es\/declaracion-de-chispa-sobre-las-elecciones\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/chispalcv.org\/wp-content\/uploads\/2023\/04\/chispaLCV.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/chispalcv.org\/wp-content\/uploads\/2023\/04\/chispaLCV.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1199\" \/>\n\t\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-11-06T18:55:03+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-11-06T18:55:10+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Declaraci\u00f3n de Chispa sobre las elecciones - Chispa | League of Conservation Voters\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Declaraci\u00f3n de la directora senior de Chispa, Estefany Carrasco-Gonz\u00e1lez, sobre los resultados de las elecciones: \u201cEstamos decepcionados por el resultado de las elecciones presidenciales, pero persistiremos y seguiremos luchando por nuestras comunidades. Bajo la nueva Administraci\u00f3n Trump, Chispa continuar\u00e1 trabajando a nivel nacional y con nuestras comunidades de primera l\u00ednea en los estados de Chispa\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/chispalcv.org\/wp-content\/uploads\/2023\/04\/chispaLCV.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/declaracion-de-chispa-sobre-las-elecciones\\\/#blogposting\",\"name\":\"Declaraci\\u00f3n de Chispa sobre las elecciones - Chispa | League of Conservation Voters\",\"headline\":\"Declaraci\\u00f3n de Chispa sobre las elecciones\",\"author\":{\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/author\\\/egaona\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/chispalcv.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Chispa-Logo.png\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/#articleImage\",\"width\":418,\"height\":80,\"caption\":\"Chispa Logo\"},\"datePublished\":\"2024-11-06T18:55:03+00:00\",\"dateModified\":\"2024-11-06T18:55:10+00:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/declaracion-de-chispa-sobre-las-elecciones\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/declaracion-de-chispa-sobre-las-elecciones\\\/#webpage\"},\"articleSection\":\"Comunicado De Prensa, Justicia Medioambiental, Latinx Poder, chispa, Elections, Justicia Medioambiental, Opcional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/declaracion-de-chispa-sobre-las-elecciones\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/category\\\/press-release-es\\\/#listItem\",\"name\":\"Comunicado De Prensa\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/category\\\/press-release-es\\\/#listItem\",\"position\":2,\"name\":\"Comunicado De Prensa\",\"item\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/category\\\/press-release-es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/declaracion-de-chispa-sobre-las-elecciones\\\/#listItem\",\"name\":\"Declaraci\\u00f3n de Chispa sobre las elecciones\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/declaracion-de-chispa-sobre-las-elecciones\\\/#listItem\",\"position\":3,\"name\":\"Declaraci\\u00f3n de Chispa sobre las elecciones\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/category\\\/press-release-es\\\/#listItem\",\"name\":\"Comunicado De Prensa\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/#organization\",\"name\":\"Chispa | League of Conservation Voters\",\"url\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/chispalcv.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Chispa-Logo.png\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/declaracion-de-chispa-sobre-las-elecciones\\\/#organizationLogo\",\"width\":418,\"height\":80,\"caption\":\"Chispa Logo\"},\"image\":{\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/declaracion-de-chispa-sobre-las-elecciones\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/author\\\/egaona\\\/#author\",\"url\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/author\\\/egaona\\\/\",\"name\":\"Elena Gaona\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/declaracion-de-chispa-sobre-las-elecciones\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e8ee127b344e8f0160475c3068d6f45a158efb02536a48c6cc3fbe45083f6ae?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Elena Gaona\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/declaracion-de-chispa-sobre-las-elecciones\\\/#webpage\",\"url\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/declaracion-de-chispa-sobre-las-elecciones\\\/\",\"name\":\"Declaraci\\u00f3n de Chispa sobre las elecciones - Chispa | League of Conservation Voters\",\"description\":\"Declaraci\\u00f3n de la directora senior de Chispa, Estefany Carrasco-Gonz\\u00e1lez, sobre los resultados de las elecciones: \\u201cEstamos decepcionados por el resultado de las elecciones presidenciales, pero persistiremos y seguiremos luchando por nuestras comunidades. Bajo la nueva Administraci\\u00f3n Trump, Chispa continuar\\u00e1 trabajando a nivel nacional y con nuestras comunidades de primera l\\u00ednea en los estados de Chispa\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/declaracion-de-chispa-sobre-las-elecciones\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/author\\\/egaona\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/author\\\/egaona\\\/#author\"},\"datePublished\":\"2024-11-06T18:55:03+00:00\",\"dateModified\":\"2024-11-06T18:55:10+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/\",\"name\":\"Chispa | League of Conservation Voters\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/chispalcv.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Declaraci\u00f3n de Chispa sobre las elecciones - Chispa | League of Conservation Voters","description":"Declaraci\u00f3n de la directora senior de Chispa, Estefany Carrasco-Gonz\u00e1lez, sobre los resultados de las elecciones: \u201cEstamos decepcionados por el resultado de las elecciones presidenciales, pero persistiremos y seguiremos luchando por nuestras comunidades. Bajo la nueva Administraci\u00f3n Trump, Chispa continuar\u00e1 trabajando a nivel nacional y con nuestras comunidades de primera l\u00ednea en los estados de Chispa","canonical_url":"https:\/\/chispalcv.org\/es\/declaracion-de-chispa-sobre-las-elecciones\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/chispalcv.org\/es\/declaracion-de-chispa-sobre-las-elecciones\/#blogposting","name":"Declaraci\u00f3n de Chispa sobre las elecciones - Chispa | League of Conservation Voters","headline":"Declaraci\u00f3n de Chispa sobre las elecciones","author":{"@id":"https:\/\/chispalcv.org\/es\/author\/egaona\/#author"},"publisher":{"@id":"https:\/\/chispalcv.org\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/chispalcv.org\/wp-content\/uploads\/2021\/08\/Chispa-Logo.png","@id":"https:\/\/chispalcv.org\/es\/#articleImage","width":418,"height":80,"caption":"Chispa Logo"},"datePublished":"2024-11-06T18:55:03+00:00","dateModified":"2024-11-06T18:55:10+00:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/chispalcv.org\/es\/declaracion-de-chispa-sobre-las-elecciones\/#webpage"},"isPartOf":{"@id":"https:\/\/chispalcv.org\/es\/declaracion-de-chispa-sobre-las-elecciones\/#webpage"},"articleSection":"Comunicado De Prensa, Justicia Medioambiental, Latinx Poder, chispa, Elections, Justicia Medioambiental, Opcional"},{"@type":"BreadcrumbList","@id":"https:\/\/chispalcv.org\/es\/declaracion-de-chispa-sobre-las-elecciones\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/chispalcv.org\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/chispalcv.org\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/chispalcv.org\/es\/category\/press-release-es\/#listItem","name":"Comunicado De Prensa"}},{"@type":"ListItem","@id":"https:\/\/chispalcv.org\/es\/category\/press-release-es\/#listItem","position":2,"name":"Comunicado De Prensa","item":"https:\/\/chispalcv.org\/es\/category\/press-release-es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/chispalcv.org\/es\/declaracion-de-chispa-sobre-las-elecciones\/#listItem","name":"Declaraci\u00f3n de Chispa sobre las elecciones"},"previousItem":{"@type":"ListItem","@id":"https:\/\/chispalcv.org\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/chispalcv.org\/es\/declaracion-de-chispa-sobre-las-elecciones\/#listItem","position":3,"name":"Declaraci\u00f3n de Chispa sobre las elecciones","previousItem":{"@type":"ListItem","@id":"https:\/\/chispalcv.org\/es\/category\/press-release-es\/#listItem","name":"Comunicado De Prensa"}}]},{"@type":"Organization","@id":"https:\/\/chispalcv.org\/es\/#organization","name":"Chispa | League of Conservation Voters","url":"https:\/\/chispalcv.org\/es\/","logo":{"@type":"ImageObject","url":"https:\/\/chispalcv.org\/wp-content\/uploads\/2021\/08\/Chispa-Logo.png","@id":"https:\/\/chispalcv.org\/es\/declaracion-de-chispa-sobre-las-elecciones\/#organizationLogo","width":418,"height":80,"caption":"Chispa Logo"},"image":{"@id":"https:\/\/chispalcv.org\/es\/declaracion-de-chispa-sobre-las-elecciones\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/chispalcv.org\/es\/author\/egaona\/#author","url":"https:\/\/chispalcv.org\/es\/author\/egaona\/","name":"Elena Gaona","image":{"@type":"ImageObject","@id":"https:\/\/chispalcv.org\/es\/declaracion-de-chispa-sobre-las-elecciones\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/0e8ee127b344e8f0160475c3068d6f45a158efb02536a48c6cc3fbe45083f6ae?s=96&d=mm&r=g","width":96,"height":96,"caption":"Elena Gaona"}},{"@type":"WebPage","@id":"https:\/\/chispalcv.org\/es\/declaracion-de-chispa-sobre-las-elecciones\/#webpage","url":"https:\/\/chispalcv.org\/es\/declaracion-de-chispa-sobre-las-elecciones\/","name":"Declaraci\u00f3n de Chispa sobre las elecciones - Chispa | League of Conservation Voters","description":"Declaraci\u00f3n de la directora senior de Chispa, Estefany Carrasco-Gonz\u00e1lez, sobre los resultados de las elecciones: \u201cEstamos decepcionados por el resultado de las elecciones presidenciales, pero persistiremos y seguiremos luchando por nuestras comunidades. Bajo la nueva Administraci\u00f3n Trump, Chispa continuar\u00e1 trabajando a nivel nacional y con nuestras comunidades de primera l\u00ednea en los estados de Chispa","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/chispalcv.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/chispalcv.org\/es\/declaracion-de-chispa-sobre-las-elecciones\/#breadcrumblist"},"author":{"@id":"https:\/\/chispalcv.org\/es\/author\/egaona\/#author"},"creator":{"@id":"https:\/\/chispalcv.org\/es\/author\/egaona\/#author"},"datePublished":"2024-11-06T18:55:03+00:00","dateModified":"2024-11-06T18:55:10+00:00"},{"@type":"WebSite","@id":"https:\/\/chispalcv.org\/es\/#website","url":"https:\/\/chispalcv.org\/es\/","name":"Chispa | League of Conservation Voters","inLanguage":"es-ES","publisher":{"@id":"https:\/\/chispalcv.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Chispa | League of Conservation Voters -","og:type":"article","og:title":"Declaraci\u00f3n de Chispa sobre las elecciones - Chispa | League of Conservation Voters","og:description":"Declaraci\u00f3n de la directora senior de Chispa, Estefany Carrasco-Gonz\u00e1lez, sobre los resultados de las elecciones: \u201cEstamos decepcionados por el resultado de las elecciones presidenciales, pero persistiremos y seguiremos luchando por nuestras comunidades. Bajo la nueva Administraci\u00f3n Trump, Chispa continuar\u00e1 trabajando a nivel nacional y con nuestras comunidades de primera l\u00ednea en los estados de Chispa","og:url":"https:\/\/chispalcv.org\/es\/declaracion-de-chispa-sobre-las-elecciones\/","og:image":"https:\/\/chispalcv.org\/wp-content\/uploads\/2023\/04\/chispaLCV.jpg","og:image:secure_url":"https:\/\/chispalcv.org\/wp-content\/uploads\/2023\/04\/chispaLCV.jpg","og:image:width":1199,"og:image:height":630,"article:published_time":"2024-11-06T18:55:03+00:00","article:modified_time":"2024-11-06T18:55:10+00:00","twitter:card":"summary_large_image","twitter:title":"Declaraci\u00f3n de Chispa sobre las elecciones - Chispa | League of Conservation Voters","twitter:description":"Declaraci\u00f3n de la directora senior de Chispa, Estefany Carrasco-Gonz\u00e1lez, sobre los resultados de las elecciones: \u201cEstamos decepcionados por el resultado de las elecciones presidenciales, pero persistiremos y seguiremos luchando por nuestras comunidades. Bajo la nueva Administraci\u00f3n Trump, Chispa continuar\u00e1 trabajando a nivel nacional y con nuestras comunidades de primera l\u00ednea en los estados de Chispa","twitter:image":"https:\/\/chispalcv.org\/wp-content\/uploads\/2023\/04\/chispaLCV.jpg"},"aioseo_meta_data":{"post_id":"5212","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-11-06 18:55:03","updated":"2025-06-11 10:02:50","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/chispalcv.org\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/chispalcv.org\/es\/category\/press-release-es\/\" title=\"Comunicado De Prensa\">Comunicado De Prensa<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDeclaraci\u00f3n de Chispa sobre las elecciones\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/chispalcv.org\/es\/"},{"label":"Comunicado De Prensa","link":"https:\/\/chispalcv.org\/es\/category\/press-release-es\/"},{"label":"Declaraci\u00f3n de Chispa sobre las elecciones","link":"https:\/\/chispalcv.org\/es\/declaracion-de-chispa-sobre-las-elecciones\/"}],"_links":{"self":[{"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/posts\/5212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/comments?post=5212"}],"version-history":[{"count":1,"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/posts\/5212\/revisions"}],"predecessor-version":[{"id":5213,"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/posts\/5212\/revisions\/5213"}],"wp:attachment":[{"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/media?parent=5212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/categories?post=5212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chispalcv.org\/es\/wp-json\/wp\/v2\/tags?post=5212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}